{"id":49655,"date":"2025-08-26T16:32:20","date_gmt":"2025-08-26T16:32:20","guid":{"rendered":"https:\/\/radionuble.cl\/v1\/?p=49655"},"modified":"2025-08-26T16:32:20","modified_gmt":"2025-08-26T16:32:20","slug":"corte-suprema-de-colombia-rechaza-extradicion-a-venezuela-de-gocho-y-abre-camino-a-que-sea-enviado-a-chile","status":"publish","type":"post","link":"https:\/\/radionuble.cl\/v1\/2025\/08\/26\/corte-suprema-de-colombia-rechaza-extradicion-a-venezuela-de-gocho-y-abre-camino-a-que-sea-enviado-a-chile\/","title":{"rendered":"Corte Suprema de Colombia rechaza extradici\u00f3n a Venezuela de \u201cGocho\u201d y abre camino a que sea enviado a Chile"},"content":{"rendered":"<p>La Corte Suprema de Justicia de Colombia rechaz\u00f3 la solicitud de extradici\u00f3n presentada por Venezuela contra Luis Alfredo Carrillo Ortiz, alias \u201cGocho\u201d, acusado de participar en el secuestro y asesinato del exmilitar venezolano Ronald Ojeda, ocurrido en Chile en febrero de 2024.<\/p>\n<p>Carrillo Ortiz, ciudadano colombo-venezolano detenido en Bogot\u00e1 en febrero pasado, es sindicado como integrante del Tren de Aragua y uno de los involucrados en el crimen que conmocion\u00f3 a Chile y a la comunidad internacional. Cabe recordar que el \u201cGocho\u201d tambi\u00e9n es requerido por la justicia chilena.<\/p>\n<p>El fallo de la Corte Suprema colombiana subraya que los delitos imputados fueron cometidos en territorio chileno, por lo que corresponde dar preferencia a la solicitud emanada de Chile. En el documento se precisa que tanto Chile como Venezuela formularon sus pedidos de extradici\u00f3n el 11 de febrero de 2025, lo que generaba una situaci\u00f3n de concurrencia.<\/p>\n<p>Sin embargo, el tribunal destac\u00f3 que el Tratado de Extradici\u00f3n de 1914 entre Colombia y Chile establece un criterio claro: la preferencia debe otorgarse al pa\u00eds en el que se cometi\u00f3 el delito de mayor gravedad.<\/p>\n<p>\u201cAs\u00ed las cosas, dado que el Tratado de Extradici\u00f3n de 1914 establece un criterio claro y espec\u00edfico para resolver casos de concurrencia de solicitudes, evidente resulta que Colombia, como pa\u00eds de asilo, deber\u00e1 preferir la extradici\u00f3n solicitada por la Rep\u00fablica de Chile por sobre la que ha sido elevada por la Rep\u00fablica Bolivariana de Venezuela\u201d, indica el fallo.<\/p>\n<p>Con esto, la justicia colombiana emiti\u00f3 un concepto desfavorable a la petici\u00f3n de Caracas, lo que allana el camino para que Carrillo Ortiz pueda ser extraditado a Chile, donde enfrentar\u00e1 cargos por secuestro con homicidio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Corte Suprema de Justicia de Colombia rechaz\u00f3 la solicitud de extradici\u00f3n presentada por Venezuela contra Luis Alfredo Carrillo Ortiz, alias \u201cGocho\u201d, acusado de participar en el secuestro y asesinato del exmilitar venezolano Ronald Ojeda, ocurrido en Chile en febrero de 2024. Carrillo Ortiz, ciudadano colombo-venezolano detenido en Bogot\u00e1 en febrero pasado, es sindicado como &hellip;<\/p>\n","protected":false},"author":1,"featured_media":49656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-49655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pais"],"_links":{"self":[{"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/posts\/49655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/comments?post=49655"}],"version-history":[{"count":1,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/posts\/49655\/revisions"}],"predecessor-version":[{"id":49657,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/posts\/49655\/revisions\/49657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/media\/49656"}],"wp:attachment":[{"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/media?parent=49655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/categories?post=49655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/tags?post=49655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}