{"id":49926,"date":"2025-09-09T15:24:06","date_gmt":"2025-09-09T15:24:06","guid":{"rendered":"https:\/\/radionuble.cl\/v1\/?p=49926"},"modified":"2025-09-09T15:24:06","modified_gmt":"2025-09-09T15:24:06","slug":"debate-presidencial-2025-jara-llega-arriba-en-las-encuestas-y-kast-promete-contraatacar","status":"publish","type":"post","link":"https:\/\/radionuble.cl\/v1\/2025\/09\/09\/debate-presidencial-2025-jara-llega-arriba-en-las-encuestas-y-kast-promete-contraatacar\/","title":{"rendered":"Debate presidencial 2025: Jara llega arriba en las encuestas y Kast promete contraatacar"},"content":{"rendered":"<p>Los candidatos presidenciales ultiman detalles antes del primer debate televisado de la campa\u00f1a, que se realizar\u00e1 este mi\u00e9rcoles a las 21:30 horas en Chilevisi\u00f3n. El encuentro reunir\u00e1 a Jeannette Jara, Jos\u00e9 Antonio Kast, Evelyn Matthei, Franco Parisi, Johannes Kaiser, Marco Enr\u00edquez-Ominami, Harold Mayne-Nicholls y Eduardo Art\u00e9s, en un momento clave que, seg\u00fan consign\u00f3 The Clinic, puede marcar un antes y un despu\u00e9s en la carrera a La Moneda.<\/p>\n<p>La candidata oficialista Jeannette Jara llega con ventaja. La \u00faltima encuesta Cadem la posiciona en el primer lugar con un 28% en primera vuelta, mientras que Criteria le otorg\u00f3 un 29%, superando por estrecho margen a Jos\u00e9 Antonio Kast, que ha perdido terreno en las \u00faltimas semanas. <\/p>\n<p>En su equipo destacan que la estrategia ser\u00e1 poner sobre la mesa los temas que recogi\u00f3 en su reciente gira nacional, donde las principales preocupaciones fueron el alto costo de la vida y las pensiones. <\/p>\n<p>Seg\u00fan adelant\u00f3 el diputado Tom\u00e1s Hirsch a The Clinic, tambi\u00e9n llevar\u00e1 una ofensiva directa contra Kast, a quien emplazar\u00e1 a explicar por qu\u00e9 quiere retroceder en el acuerdo previsional, lo que significar\u00eda, en palabras del parlamentario, que los jubilados pierdan cerca de 80 mil pesos al mes.<\/p>\n<p>Desde el comando de Jos\u00e9 Antonio Kast aseguran que el debate puede ser gravitante. Recuerdan que en 2021 su nombre subi\u00f3 en los sondeos gracias a su desempe\u00f1o en estas instancias, aunque admiten que en segunda vuelta frente a Gabriel Boric no tuvo el mismo resultado. <\/p>\n<p>En esta ocasi\u00f3n, el republicano se prepara con minutas y asesor\u00edas de su c\u00edrculo m\u00e1s cercano, con el objetivo de consolidar su primer lugar y marcar una clara distancia con la candidata oficialista, con quien se disputa voto a voto el liderazgo en las encuestas.<\/p>\n<p>Evelyn Matthei, en tanto, busca consolidar el repunte que muestran los \u00faltimos sondeos. Su comando la ha preparado intensamente para demostrar que \u201csabe y puede\u201d liderar los cambios que Chile necesita, destacando su experiencia y capacidad de convocar equipos s\u00f3lidos. <\/p>\n<p>La candidata de Chile Vamos cuenta con el apoyo de asesores como Mat\u00edas de la Fuente, ex jefe de gabinete del expresidente Ricardo Lagos, y de su hist\u00f3rico colaborador Cristian Torres, adem\u00e1s de figuras pol\u00edticas que se sumaron al relanzamiento de su campa\u00f1a. El desaf\u00edo, seg\u00fan The Clinic, ser\u00e1 instalar su discurso con claridad y diferenciarse de Kast para asegurar un cupo en segunda vuelta.<\/p>\n<p>El resto de los candidatos tambi\u00e9n afinan detalles. Marco Enr\u00edquez-Ominami insiste en que no necesita un coach y que su fortaleza est\u00e1 en la experiencia de cuatro campa\u00f1as presidenciales anteriores. Franco Parisi prepara decenas de preguntas para sus rivales y busca instalar al Partido de la Gente como la alternativa frente a los extremos. <\/p>\n<p>Johannes Kaiser ha trabajado con sparrings para simular el debate y mostrar preparaci\u00f3n en seguridad y econom\u00eda, mientras Harold Mayne-Nicholls debutar\u00e1 en este formato intentando proyectar seriedad en sus propuestas. Eduardo Art\u00e9s, en cambio, le resta dramatismo al evento y asegura que es solo una actividad m\u00e1s dentro de su campa\u00f1a.<\/p>\n<p>Seg\u00fan analistas consultados por The Clinic, este debate puede ser determinante en el escenario presidencial, pues se da a menos de setenta d\u00edas de la primera vuelta y en un ambiente pol\u00edtico polarizado. <\/p>\n<p>Cada candidato intentar\u00e1 no solo convencer a los indecisos, sino tambi\u00e9n marcar un sello que lo diferencie de sus contendores en una campa\u00f1a donde las encuestas ya muestran movimientos significativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los candidatos presidenciales ultiman detalles antes del primer debate televisado de la campa\u00f1a, que se realizar\u00e1 este mi\u00e9rcoles a las 21:30 horas en Chilevisi\u00f3n. El encuentro reunir\u00e1 a Jeannette Jara, Jos\u00e9 Antonio Kast, Evelyn Matthei, Franco Parisi, Johannes Kaiser, Marco Enr\u00edquez-Ominami, Harold Mayne-Nicholls y Eduardo Art\u00e9s, en un momento clave que, seg\u00fan consign\u00f3 The Clinic, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":49927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-49926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pais"],"_links":{"self":[{"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/posts\/49926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/comments?post=49926"}],"version-history":[{"count":1,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/posts\/49926\/revisions"}],"predecessor-version":[{"id":49928,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/posts\/49926\/revisions\/49928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/media\/49927"}],"wp:attachment":[{"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/media?parent=49926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/categories?post=49926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radionuble.cl\/v1\/wp-json\/wp\/v2\/tags?post=49926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}